{"id":1163,"date":"2021-06-22T16:42:24","date_gmt":"2021-06-22T16:42:24","guid":{"rendered":"https:\/\/exbaconsulting.com\/?p=1163"},"modified":"2021-06-22T18:49:29","modified_gmt":"2021-06-22T18:49:29","slug":"ciencia-de-datos-la-carrera-que-estabas-esperando","status":"publish","type":"post","link":"https:\/\/exbaconsulting.com\/en\/ciencia-de-datos-la-carrera-que-estabas-esperando\/","title":{"rendered":"Ciencia de Datos: la carrera que estabas esperando"},"content":{"rendered":"<p><span style=\"font-weight: 400\">A ra\u00edz de esta pandemia que atraviesa a la humanidad, han surgido m\u00faltiples respuestas y reacciones de la sociedad que tienen que ver con el poder de adaptaci\u00f3n y de supervivencia del ser humano. Ya hemos hablado sobre c\u00f3mo se transform\u00f3 la educaci\u00f3n presencial a un formato virtual en nuestro art\u00edculo <\/span><a href=\"https:\/\/exbaconsulting.com\/en\/e-learning-como-metodo-de-estudio\/\"><span style=\"font-weight: 400\">\u201cE-learning: el futuro, antes de lo previsto\u201d<\/span><\/a><span style=\"font-weight: 400\">; tambi\u00e9n fuimos testigos de la velocidad con la que los cient\u00edficos de todo el mundo han creado <\/span><a href=\"https:\/\/www.argentina.gob.ar\/coronavirus\/vacuna\/cuales\"><span style=\"font-weight: 400\">vacunas <\/span><\/a><span style=\"font-weight: 400\">para enfrentar a este virus. Estos son solo algunos de los miles de ejemplos que tenemos para tomar consciencia sobre lo que viene sucediendo. Es por todo esto que no nos deber\u00eda sorprender que, como consecuencia, se haya creado una nueva carrera universitaria que se dicta en la <\/span><a href=\"https:\/\/www.unab.edu.ar\/lic-ciencia-datos.html\"><span style=\"font-weight: 400\">Universidad de Guillermo Brown<\/span><\/a><span style=\"font-weight: 400\"> y, recientemente, en la UBA en la facultad de Ciencias exactas y Naturales: <\/span><a href=\"https:\/\/exactas.uba.ar\/ensenanza\/carreras-de-grado\/ciencias-de-datos\/\"><span style=\"font-weight: 400\">la licenciatura en Ciencias de Datos<\/span><\/a><span style=\"font-weight: 400\">.<\/span><\/p>\n<p><span style=\"font-weight: 400\">Pero \u00bfqu\u00e9 es un dato? Un <\/span><a href=\"https:\/\/concepto.de\/dato\/\"><span style=\"font-weight: 400\">dato<\/span><\/a><span style=\"font-weight: 400\"> es <\/span><span style=\"font-weight: 400\">la representaci\u00f3n de una <\/span><a href=\"https:\/\/concepto.de\/variable\/\"><span style=\"font-weight: 400\">variable<\/span><\/a><span style=\"font-weight: 400\"> que puede ser cuantitativa o cualitativa, que <\/span><span style=\"font-weight: 400\">indica un valor que se le asigna a las cosas y se representa a trav\u00e9s de una secuencia de s\u00edmbolos, n\u00fameros o letras<\/span><span style=\"font-weight: 400\">. Por consiguiente, la carrera de grado en Ciencias de Datos tiene como objetivo capacitar a los estudiantes en el dominio de grandes vol\u00famenes de datos, ya que el crecimiento en la capacidad de c\u00f3mputo y almacenamiento y la conectividad cambiaron la potencialidad del <\/span><a href=\"https:\/\/es.wikipedia.org\/wiki\/An%C3%A1lisis_num%C3%A9rico\"><span style=\"font-weight: 400\">an\u00e1lisis num\u00e9rico<\/span><\/a><span style=\"font-weight: 400\"> y de la <\/span><a href=\"https:\/\/www.iberdrola.com\/innovacion\/que-es-inteligencia-artificial\"><span style=\"font-weight: 400\">inteligencia artificial<\/span><\/a><span style=\"font-weight: 400\">. La utilizaci\u00f3n de la informaci\u00f3n analizada tendr\u00e1 que ver con el campo en el que se est\u00e9 realizando el estudio.<\/span> <span style=\"font-weight: 400\">Puede ser desde comprender y analizar una tabla de valores, la distribuci\u00f3n de ingresos en una poblaci\u00f3n, la comparaci\u00f3n de alturas en ni\u00f1os de \u201cX\u201d a\u00f1os, o bien, la econom\u00eda y los niveles de productividad de una naci\u00f3n. Luego del an\u00e1lisis de la informaci\u00f3n comparada, lo que viene es entrenarse en extraer conclusiones interesantes.\u00a0<\/span><\/p>\n<p><b>\u00bfPor qu\u00e9 deber\u00edamos considerar la Licenciatura en Ciencias de Datos? <\/b><span style=\"font-weight: 400\">\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400\">Porque un licenciado en Ciencias de Datos adquirir\u00e1 una f<\/span><span style=\"font-weight: 400\">ormaci\u00f3n cient\u00edfica en computaci\u00f3n, matem\u00e1tica y datos. Esto te permitir\u00e1 una r\u00e1pida inserci\u00f3n en el sector p\u00fablico, en el sector productivo y de servicios y tambi\u00e9n la interacci\u00f3n con grupos de investigaci\u00f3n de las m\u00e1s diversas disciplinas cient\u00edficas, desde la biolog\u00eda o la agronom\u00eda hasta la f\u00edsica, la qu\u00edmica o el estudio de la atm\u00f3sfera.<\/span><span style=\"font-weight: 400\"> Hasta ahora suena todo muy acad\u00e9mico \u00bfverdad? pero otra excelente motivaci\u00f3n que te podemos dar para que te atrevas a considerar esta carrera para tu futuro, es que tiene mucha demanda laboral y los sueldos que se pagan a los profesionales son los m\u00e1s altos del pa\u00eds. S\u00ed, cr\u00e9enos. Grandes empresas nacionales e internacionales como <\/span><b>Mercado libre<\/b><span style=\"font-weight: 400\">, <\/span><b>Telef\u00f3nica<\/b><span style=\"font-weight: 400\">, <\/span><b>Globant<\/b><span style=\"font-weight: 400\">, <\/span><b>Banco Galicia<\/b><span style=\"font-weight: 400\">, entre muchos otros, demandan incorporar <\/span><a href=\"https:\/\/www.sas.com\/en_us\/insights\/analytics\/what-is-a-data-scientist.html\"><span style=\"font-weight: 400\">Data Scientist<\/span><\/a><span style=\"font-weight: 400\"> a sus equipos, dada la alt\u00edsima y constante variaci\u00f3n en la poblaci\u00f3n y, por l\u00f3gica, en las necesidades de sus clientes. <\/span><span style=\"font-weight: 400\">No es una informaci\u00f3n menor saber que la Argentina lidera la regi\u00f3n LATAM, seg\u00fan un informe realizado por la plataforma de educaci\u00f3n virtual de la<\/span><a href=\"https:\/\/www.stanford.edu\/\"><span style=\"font-weight: 400\"> Universidad de Stanford<\/span><\/a><span style=\"font-weight: 400\">, donde se analizaron las habilidades tecnol\u00f3gicas de distintas poblaciones. Este pa\u00eds se posicion\u00f3 como el mejor en habilidades tecnol\u00f3gicas en Data Science y en habilidades IT. Para el informe tuvieron en cuenta conocimientos en <\/span><b>matem\u00e1tica<\/b><span style=\"font-weight: 400\">, <\/span><b>estad\u00edstica<\/b><span style=\"font-weight: 400\">, <\/span><b>aprendizaje automatizado<\/b><span style=\"font-weight: 400\">, <\/span><b>visualizaci\u00f3n y m<\/b><b>anejo de datos<\/b> <b>y<\/b> <b>programaci\u00f3n en idioma R, Python, SQL y otros<\/b><span style=\"font-weight: 400\">.<\/span><\/p>\n<p><img class=\"wp-image-1166 aligncenter\" src=\"https:\/\/exbaconsulting.com\/wp-content\/uploads\/2021\/06\/Diseno-sin-titulo-1-300x200.png\" alt=\"\" width=\"409\" height=\"273\" srcset=\"https:\/\/exbaconsulting.com\/wp-content\/uploads\/2021\/06\/Diseno-sin-titulo-1-300x200.png 300w, https:\/\/exbaconsulting.com\/wp-content\/uploads\/2021\/06\/Diseno-sin-titulo-1-1024x683.png 1024w, https:\/\/exbaconsulting.com\/wp-content\/uploads\/2021\/06\/Diseno-sin-titulo-1-768x512.png 768w, https:\/\/exbaconsulting.com\/wp-content\/uploads\/2021\/06\/Diseno-sin-titulo-1-16x12.png 16w, https:\/\/exbaconsulting.com\/wp-content\/uploads\/2021\/06\/Diseno-sin-titulo-1.png 1200w\" sizes=\"(max-width: 409px) 100vw, 409px\" \/><\/p>\n<p><span style=\"font-weight: 400\">Tal y como venimos inform\u00e1ndote en <\/span><a href=\"https:\/\/exbaconsulting.com\/en\/\"><span style=\"font-weight: 400\">Experiencie Baires<\/span><\/a><span style=\"font-weight: 400\">, la tecnolog\u00eda es la protagonista indiscutida en cada movimiento del ser humano: los desaf\u00edos se renovaron y los conocimientos requeridos cambiaron. Es por todo esto que te recomendamos que contin\u00faes investigando, analizando, estudiando y capacit\u00e1ndote en todo lo nuevo que sale al mercado y en todas las actualizaciones de lo que ya exist\u00eda. Si te gust\u00f3 este art\u00edculo, comp\u00e1rtelo y qu\u00e9date atento a las pr\u00f3ximas novedades que estaremos subiendo.\u00a0<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400\">Marcela Gangemi <\/span><\/p>","protected":false},"excerpt":{"rendered":"<p>A ra\u00edz de esta pandemia que atraviesa a la humanidad, han surgido m\u00faltiples respuestas y reacciones de la sociedad que tienen que ver con el poder de adaptaci\u00f3n y de supervivencia del ser humano. Ya hemos hablado sobre c\u00f3mo se transform\u00f3 la educaci\u00f3n presencial a un formato virtual en nuestro art\u00edculo \u201cE-learning: el futuro, antes &hellip;<\/p>\n<p class=\"read-more\"> <a class=\"\" href=\"https:\/\/exbaconsulting.com\/en\/ciencia-de-datos-la-carrera-que-estabas-esperando\/\"> <span class=\"screen-reader-text\">Ciencia de Datos: la carrera que estabas esperando<\/span> Read More &raquo;<\/a><\/p>","protected":false},"author":5,"featured_media":1166,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[12,27],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v16.9 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Ciencia de Datos: la carrera que estabas esperando - exbaconsulting<\/title>\n<meta name=\"description\" content=\"La ciencia de datos es un campo interdisciplinario que hace uso de diferentes tecnolog\u00edas y m\u00e9todos como el an\u00e1lisis num\u00e9rico y la inteligencia artificial.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/exbaconsulting.com\/en\/ciencia-de-datos-la-carrera-que-estabas-esperando\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ciencia de Datos: la carrera que estabas esperando - exbaconsulting\" \/>\n<meta property=\"og:description\" content=\"La ciencia de datos es un campo interdisciplinario que hace uso de diferentes tecnolog\u00edas y m\u00e9todos como el an\u00e1lisis num\u00e9rico y la inteligencia artificial.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/exbaconsulting.com\/en\/ciencia-de-datos-la-carrera-que-estabas-esperando\/\" \/>\n<meta property=\"og:site_name\" content=\"exbaconsulting\" \/>\n<meta property=\"article:published_time\" content=\"2021-06-22T16:42:24+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-06-22T18:49:29+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/experiencebaires.com\/wp-content\/uploads\/2021\/06\/Diseno-sin-titulo-1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Copywriter-expba\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Organization\",\"@id\":\"https:\/\/exbaconsulting.com\/en\/#organization\",\"name\":\"Experience Baires\",\"url\":\"https:\/\/exbaconsulting.com\/en\/\",\"sameAs\":[],\"logo\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/exbaconsulting.com\/en\/#logo\",\"inLanguage\":\"en-US\",\"url\":\"https:\/\/exbaconsulting.com\/wp-content\/uploads\/2020\/10\/Artboard-1-copy-9-8.png\",\"contentUrl\":\"https:\/\/exbaconsulting.com\/wp-content\/uploads\/2020\/10\/Artboard-1-copy-9-8.png\",\"width\":769,\"height\":355,\"caption\":\"Experience Baires\"},\"image\":{\"@id\":\"https:\/\/exbaconsulting.com\/en\/#logo\"}},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/exbaconsulting.com\/en\/#website\",\"url\":\"https:\/\/exbaconsulting.com\/en\/\",\"name\":\"exbaconsulting\",\"description\":\"En EXBA ofrecemos enfoque innovador orientado a proveer servicios digitales que abarca desde el marketing digital y el comercio electr\\u00f3nico. hasta el desarrollo web y el an\\u00e1lisis de datos y la creaci\\u00f3n de aplicaciones.\",\"publisher\":{\"@id\":\"https:\/\/exbaconsulting.com\/en\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/exbaconsulting.com\/en\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/exbaconsulting.com\/en\/ciencia-de-datos-la-carrera-que-estabas-esperando\/#primaryimage\",\"inLanguage\":\"en-US\",\"url\":\"https:\/\/exbaconsulting.com\/wp-content\/uploads\/2021\/06\/Diseno-sin-titulo-1.png\",\"contentUrl\":\"https:\/\/exbaconsulting.com\/wp-content\/uploads\/2021\/06\/Diseno-sin-titulo-1.png\",\"width\":1200,\"height\":800},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/exbaconsulting.com\/en\/ciencia-de-datos-la-carrera-que-estabas-esperando\/#webpage\",\"url\":\"https:\/\/exbaconsulting.com\/en\/ciencia-de-datos-la-carrera-que-estabas-esperando\/\",\"name\":\"Ciencia de Datos: la carrera que estabas esperando - exbaconsulting\",\"isPartOf\":{\"@id\":\"https:\/\/exbaconsulting.com\/en\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/exbaconsulting.com\/en\/ciencia-de-datos-la-carrera-que-estabas-esperando\/#primaryimage\"},\"datePublished\":\"2021-06-22T16:42:24+00:00\",\"dateModified\":\"2021-06-22T18:49:29+00:00\",\"description\":\"La ciencia de datos es un campo interdisciplinario que hace uso de diferentes tecnolog\\u00edas y m\\u00e9todos como el an\\u00e1lisis num\\u00e9rico y la inteligencia artificial.\",\"breadcrumb\":{\"@id\":\"https:\/\/exbaconsulting.com\/en\/ciencia-de-datos-la-carrera-que-estabas-esperando\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/exbaconsulting.com\/en\/ciencia-de-datos-la-carrera-que-estabas-esperando\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/exbaconsulting.com\/en\/ciencia-de-datos-la-carrera-que-estabas-esperando\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/exbaconsulting.com\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ciencia de Datos: la carrera que estabas esperando\"}]},{\"@type\":\"Article\",\"@id\":\"https:\/\/exbaconsulting.com\/en\/ciencia-de-datos-la-carrera-que-estabas-esperando\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/exbaconsulting.com\/en\/ciencia-de-datos-la-carrera-que-estabas-esperando\/#webpage\"},\"author\":{\"@id\":\"https:\/\/exbaconsulting.com\/en\/#\/schema\/person\/02316c933fb5acd93ce7dbaac661cfe6\"},\"headline\":\"Ciencia de Datos: la carrera que estabas esperando\",\"datePublished\":\"2021-06-22T16:42:24+00:00\",\"dateModified\":\"2021-06-22T18:49:29+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/exbaconsulting.com\/en\/ciencia-de-datos-la-carrera-que-estabas-esperando\/#webpage\"},\"wordCount\":722,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/exbaconsulting.com\/en\/#organization\"},\"image\":{\"@id\":\"https:\/\/exbaconsulting.com\/en\/ciencia-de-datos-la-carrera-que-estabas-esperando\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/exbaconsulting.com\/wp-content\/uploads\/2021\/06\/Diseno-sin-titulo-1.png\",\"articleSection\":[\"An\\u00e1lisis de Datos\",\"Transformaci\\u00f3n Digital\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/exbaconsulting.com\/en\/ciencia-de-datos-la-carrera-que-estabas-esperando\/#respond\"]}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/exbaconsulting.com\/en\/#\/schema\/person\/02316c933fb5acd93ce7dbaac661cfe6\",\"name\":\"Copywriter-expba\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/exbaconsulting.com\/en\/#personlogo\",\"inLanguage\":\"en-US\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/e1aabedcf35b9eafdc8f96461f500400?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/e1aabedcf35b9eafdc8f96461f500400?s=96&d=mm&r=g\",\"caption\":\"Copywriter-expba\"},\"url\":\"https:\/\/exbaconsulting.com\/en\/author\/copywriter-expba\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ciencia de Datos: la carrera que estabas esperando - exbaconsulting","description":"La ciencia de datos es un campo interdisciplinario que hace uso de diferentes tecnolog\u00edas y m\u00e9todos como el an\u00e1lisis num\u00e9rico y la inteligencia artificial.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/exbaconsulting.com\/en\/ciencia-de-datos-la-carrera-que-estabas-esperando\/","og_locale":"en_US","og_type":"article","og_title":"Ciencia de Datos: la carrera que estabas esperando - exbaconsulting","og_description":"La ciencia de datos es un campo interdisciplinario que hace uso de diferentes tecnolog\u00edas y m\u00e9todos como el an\u00e1lisis num\u00e9rico y la inteligencia artificial.","og_url":"https:\/\/exbaconsulting.com\/en\/ciencia-de-datos-la-carrera-que-estabas-esperando\/","og_site_name":"exbaconsulting","article_published_time":"2021-06-22T16:42:24+00:00","article_modified_time":"2021-06-22T18:49:29+00:00","og_image":[{"width":1200,"height":800,"url":"https:\/\/experiencebaires.com\/wp-content\/uploads\/2021\/06\/Diseno-sin-titulo-1.png","path":"\/home\/u464675711\/domains\/experiencebaires.com\/public_html\/wp-content\/uploads\/2021\/06\/Diseno-sin-titulo-1.png","size":"full","id":1166,"alt":"","pixels":960000,"type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Written by":"Copywriter-expba","Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Organization","@id":"https:\/\/exbaconsulting.com\/en\/#organization","name":"Experience Baires","url":"https:\/\/exbaconsulting.com\/en\/","sameAs":[],"logo":{"@type":"ImageObject","@id":"https:\/\/exbaconsulting.com\/en\/#logo","inLanguage":"en-US","url":"https:\/\/exbaconsulting.com\/wp-content\/uploads\/2020\/10\/Artboard-1-copy-9-8.png","contentUrl":"https:\/\/exbaconsulting.com\/wp-content\/uploads\/2020\/10\/Artboard-1-copy-9-8.png","width":769,"height":355,"caption":"Experience Baires"},"image":{"@id":"https:\/\/exbaconsulting.com\/en\/#logo"}},{"@type":"WebSite","@id":"https:\/\/exbaconsulting.com\/en\/#website","url":"https:\/\/exbaconsulting.com\/en\/","name":"exbaconsulting","description":"En EXBA ofrecemos enfoque innovador orientado a proveer servicios digitales que abarca desde el marketing digital y el comercio electr\u00f3nico. hasta el desarrollo web y el an\u00e1lisis de datos y la creaci\u00f3n de aplicaciones.","publisher":{"@id":"https:\/\/exbaconsulting.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/exbaconsulting.com\/en\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"},{"@type":"ImageObject","@id":"https:\/\/exbaconsulting.com\/en\/ciencia-de-datos-la-carrera-que-estabas-esperando\/#primaryimage","inLanguage":"en-US","url":"https:\/\/exbaconsulting.com\/wp-content\/uploads\/2021\/06\/Diseno-sin-titulo-1.png","contentUrl":"https:\/\/exbaconsulting.com\/wp-content\/uploads\/2021\/06\/Diseno-sin-titulo-1.png","width":1200,"height":800},{"@type":"WebPage","@id":"https:\/\/exbaconsulting.com\/en\/ciencia-de-datos-la-carrera-que-estabas-esperando\/#webpage","url":"https:\/\/exbaconsulting.com\/en\/ciencia-de-datos-la-carrera-que-estabas-esperando\/","name":"Ciencia de Datos: la carrera que estabas esperando - exbaconsulting","isPartOf":{"@id":"https:\/\/exbaconsulting.com\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/exbaconsulting.com\/en\/ciencia-de-datos-la-carrera-que-estabas-esperando\/#primaryimage"},"datePublished":"2021-06-22T16:42:24+00:00","dateModified":"2021-06-22T18:49:29+00:00","description":"La ciencia de datos es un campo interdisciplinario que hace uso de diferentes tecnolog\u00edas y m\u00e9todos como el an\u00e1lisis num\u00e9rico y la inteligencia artificial.","breadcrumb":{"@id":"https:\/\/exbaconsulting.com\/en\/ciencia-de-datos-la-carrera-que-estabas-esperando\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/exbaconsulting.com\/en\/ciencia-de-datos-la-carrera-que-estabas-esperando\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/exbaconsulting.com\/en\/ciencia-de-datos-la-carrera-que-estabas-esperando\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/exbaconsulting.com\/en\/"},{"@type":"ListItem","position":2,"name":"Ciencia de Datos: la carrera que estabas esperando"}]},{"@type":"Article","@id":"https:\/\/exbaconsulting.com\/en\/ciencia-de-datos-la-carrera-que-estabas-esperando\/#article","isPartOf":{"@id":"https:\/\/exbaconsulting.com\/en\/ciencia-de-datos-la-carrera-que-estabas-esperando\/#webpage"},"author":{"@id":"https:\/\/exbaconsulting.com\/en\/#\/schema\/person\/02316c933fb5acd93ce7dbaac661cfe6"},"headline":"Ciencia de Datos: la carrera que estabas esperando","datePublished":"2021-06-22T16:42:24+00:00","dateModified":"2021-06-22T18:49:29+00:00","mainEntityOfPage":{"@id":"https:\/\/exbaconsulting.com\/en\/ciencia-de-datos-la-carrera-que-estabas-esperando\/#webpage"},"wordCount":722,"commentCount":0,"publisher":{"@id":"https:\/\/exbaconsulting.com\/en\/#organization"},"image":{"@id":"https:\/\/exbaconsulting.com\/en\/ciencia-de-datos-la-carrera-que-estabas-esperando\/#primaryimage"},"thumbnailUrl":"https:\/\/exbaconsulting.com\/wp-content\/uploads\/2021\/06\/Diseno-sin-titulo-1.png","articleSection":["An\u00e1lisis de Datos","Transformaci\u00f3n Digital"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/exbaconsulting.com\/en\/ciencia-de-datos-la-carrera-que-estabas-esperando\/#respond"]}]},{"@type":"Person","@id":"https:\/\/exbaconsulting.com\/en\/#\/schema\/person\/02316c933fb5acd93ce7dbaac661cfe6","name":"Copywriter-expba","image":{"@type":"ImageObject","@id":"https:\/\/exbaconsulting.com\/en\/#personlogo","inLanguage":"en-US","url":"https:\/\/secure.gravatar.com\/avatar\/e1aabedcf35b9eafdc8f96461f500400?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e1aabedcf35b9eafdc8f96461f500400?s=96&d=mm&r=g","caption":"Copywriter-expba"},"url":"https:\/\/exbaconsulting.com\/en\/author\/copywriter-expba\/"}]}},"_links":{"self":[{"href":"https:\/\/exbaconsulting.com\/en\/wp-json\/wp\/v2\/posts\/1163"}],"collection":[{"href":"https:\/\/exbaconsulting.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/exbaconsulting.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/exbaconsulting.com\/en\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/exbaconsulting.com\/en\/wp-json\/wp\/v2\/comments?post=1163"}],"version-history":[{"count":0,"href":"https:\/\/exbaconsulting.com\/en\/wp-json\/wp\/v2\/posts\/1163\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/exbaconsulting.com\/en\/wp-json\/wp\/v2\/media\/1166"}],"wp:attachment":[{"href":"https:\/\/exbaconsulting.com\/en\/wp-json\/wp\/v2\/media?parent=1163"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/exbaconsulting.com\/en\/wp-json\/wp\/v2\/categories?post=1163"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/exbaconsulting.com\/en\/wp-json\/wp\/v2\/tags?post=1163"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}